{"id":131768,"date":"2016-06-03T15:49:26","date_gmt":"2016-06-03T19:49:26","guid":{"rendered":"http:\/\/www.extraderondonia.com.br\/?p=131768"},"modified":"2016-06-05T12:45:02","modified_gmt":"2016-06-05T16:45:02","slug":"expocol-baile-da-rainha-sera-neste-sabado","status":"publish","type":"post","link":"https:\/\/www.extraderondonia.com.br\/sistema\/2016\/06\/03\/expocol-baile-da-rainha-sera-neste-sabado\/","title":{"rendered":"EXPOCOL: baile da Rainha ser\u00e1 neste s\u00e1bado"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-131769\" src=\"http:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2016\/06\/13335261_893770200727040_483576265_n-300x200.jpg\" alt=\"13335261_893770200727040_483576265_n\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2016\/06\/13335261_893770200727040_483576265_n-300x200.jpg 300w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2016\/06\/13335261_893770200727040_483576265_n-630x420.jpg 630w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2016\/06\/13335261_893770200727040_483576265_n-600x400.jpg 600w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2016\/06\/13335261_893770200727040_483576265_n.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Neste s\u00e1bado,4, nova candidatas v\u00e3o disputar o t\u00edtulo de representante da beleza da Expocol 2016.<\/p>\n<p>O baile para escolha da Rainha vai acontecer no CTG Saudade da Quer\u00eancia e vai contar com v\u00e1rias atra\u00e7\u00f5es.<\/p>\n<p>A noite contar\u00e1 com anima\u00e7\u00e3o do show da dupla Jo\u00e3o Pedro &amp; Luan.\u00a0As mesas e convites individuais para o evento j\u00e1 est\u00e3o \u00e0 venda.<\/p>\n<p>Os ingressos custam R$ 25,00, e as mesas est\u00e3o sendo vendidas por R$ 100.\u00a0Mais informa\u00e7\u00f5es do evento podem ser obtidas atrav\u00e9s do \u00a0telefone (69)8414 8138.<\/p>\n<p>Texto: Extra de Rond\u00f4nia<\/p>\n<p>Foto: Divulga\u00e7\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Neste s\u00e1bado,4, nova candidatas v\u00e3o disputar o t\u00edtulo de representante da beleza da Expocol 2016. O baile para escolha da Rainha vai acontecer no CTG Saudade da Quer\u00eancia e vai contar com v\u00e1rias atra\u00e7\u00f5es. A noite contar\u00e1 com anima\u00e7\u00e3o do show da dupla Jo\u00e3o Pedro &amp; Luan.\u00a0As mesas e convites individuais para o evento [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":131769,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-131768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/131768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/comments?post=131768"}],"version-history":[{"count":0,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/131768\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media\/131769"}],"wp:attachment":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media?parent=131768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/categories?post=131768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/tags?post=131768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}