{"id":197432,"date":"2017-11-03T15:09:10","date_gmt":"2017-11-03T19:09:10","guid":{"rendered":"http:\/\/www.extraderondonia.com.br\/?p=197432"},"modified":"2017-11-03T15:09:10","modified_gmt":"2017-11-03T19:09:10","slug":"sesdec-abre-inscricao-para-candidatos-interessados-em-servico-voluntario-em-11-municipios-de-rondonia","status":"publish","type":"post","link":"https:\/\/www.extraderondonia.com.br\/sistema\/2017\/11\/03\/sesdec-abre-inscricao-para-candidatos-interessados-em-servico-voluntario-em-11-municipios-de-rondonia\/","title":{"rendered":"Sesdec abre inscri\u00e7\u00e3o para candidatos interessados em servi\u00e7o volunt\u00e1rio em 11 munic\u00edpios de Rond\u00f4nia"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-197433\" src=\"http:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2017\/11\/Projeto-voluntariar-370x491-226x300.png\" alt=\"\" width=\"226\" height=\"300\" srcset=\"https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2017\/11\/Projeto-voluntariar-370x491-226x300.png 226w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2017\/11\/Projeto-voluntariar-370x491-316x420.png 316w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2017\/11\/Projeto-voluntariar-370x491.png 370w\" sizes=\"auto, (max-width: 226px) 100vw, 226px\" \/>A Secretaria de Estado da Seguran\u00e7a, Defesa e Cidadania (Sesdec) torna p\u00fablico que a partir de segunda-feira (6) at\u00e9 o dia 27\/11, estar\u00e3o abertas as inscri\u00e7\u00f5es para candidatos interessados em prestar servi\u00e7o volunt\u00e1rio nas Estruturas Administrativas das Unidades Integradas de Seguran\u00e7a P\u00fablica-Unisps, na Capital e no interior do Estado, nas categorias de servi\u00e7o volunt\u00e1rio social e servi\u00e7o volunt\u00e1rio profissional. O processo seletivo ser\u00e1 regido pelo Edital 001\/2017 que foi publicado no dia 31 de outubro.<\/p>\n<p>A inscri\u00e7\u00e3o dever\u00e1 ser realizada por meio do Portal de Processos Seletivos do Governo do Estado de Rond\u00f4nia atrav\u00e9s do link que disponibiliza o Edital e a Ficha de Inscri\u00e7\u00e3o que dever\u00e1 ser preenchida com dados pessoais do candidato e demais informa\u00e7\u00f5es. N\u00e3o ser\u00e1 cobrada nenhuma taxa de inscri\u00e7\u00e3o.<\/p>\n<p>Conforme explicou o ouvidor da Sesdec, Leandro Picoreli, o servi\u00e7o volunt\u00e1rio ser\u00e1 prestado de forma espont\u00e2nea e ter\u00e1 o prazo de dura\u00e7\u00e3o de at\u00e9 um ano, prorrog\u00e1vel uma vez por igual per\u00edodo, n\u00e3o gera v\u00ednculo funcional ou qualquer obriga\u00e7\u00e3o de natureza trabalhista, previdenci\u00e1ria ou afim e qualquer pessoa f\u00edsica que se enquadre nos termos estabelecidos no edital pode se inscrever, sendo a idade m\u00ednima de 18 anos e possuir Idoneidade Moral.<\/p>\n<p>A presta\u00e7\u00e3o do servi\u00e7o volunt\u00e1rio se dar\u00e1 em quaisquer \u00e1reas do conhecimento, que abranjam as seguintes categorias: Servi\u00e7o Volunt\u00e1rio Social que ser\u00e1 prestado por pessoa f\u00edsica da comunidade, que tenha objetivos c\u00edvicos e de promo\u00e7\u00e3o e exerc\u00edcio dos direitos humanos, culturais, recreativos ou assistenciais, nas \u00e1reas de sa\u00fade, educa\u00e7\u00e3o, esporte, lazer, cultura, meio ambiente, defesa social e jur\u00eddica, seguran\u00e7a p\u00fablica, dentre outros.<\/p>\n<p>J\u00e1 o Servi\u00e7o Volunt\u00e1rio Profissional ser\u00e1 prestado de forma complementar, por pessoa f\u00edsica com forma\u00e7\u00e3o nas \u00e1reas de sa\u00fade, educa\u00e7\u00e3o, seguran\u00e7a p\u00fablica, esporte, lazer, cultura, meio ambiente, assist\u00eancia e defesa social e jur\u00eddica, dentre outros. \u201cAo volunt\u00e1rio somente ser\u00e3o cometidas tarefas e responsabilidades compat\u00edveis com o conhecimento, experi\u00eancia e interesses declarados por ocasi\u00e3o de sua inscri\u00e7\u00e3o\u201d, acrescentou o Ouvidor da Sesdec.<\/p>\n<p>A jornada de trabalho envolve uma carga hor\u00e1ria m\u00ednima de seis horas por dia, de segunda-feira a sexta-feira, a ser exercida no hor\u00e1rio das 7h30 \u00e0s 13h30 e o prestador do servi\u00e7o volunt\u00e1rio poder\u00e1 ser ressarcido pelas despesas com transportes e alimenta\u00e7\u00e3o no valor de R$ 35,00 por dia, efetivamente trabalhado.<\/p>\n<p><strong>VAGAS<\/strong><\/p>\n<p>Ser\u00e3o ofertadas, neste Processo Seletivo, 50 vagas para candidatos que se interessam em prestar servi\u00e7o volunt\u00e1rio nas Unisps-Sesdec, sendo em Porto Velho 22 vagas que ser\u00e3o distribu\u00eddas nas Unisps Leste, Sul e Centro; Ariquemes (7), Ji-Paran\u00e1 (7), Colorado (1). Cujubim (1), Espig\u00e3o do Oeste (1), Ouro Preto do Oeste (1), Machadinho do Oeste (1), Nova Brasil\u00e2ndia (1), Rolim de Moura (1) e Vilhena (7).<\/p>\n<p><a href=\"http:\/\/www.diof.ro.gov.br\/data\/uploads\/2017\/11\/DOE-31_10_2017.pdf\">LINK EDITAL<\/a><\/p>\n<p><a href=\"http:\/\/processoseletivo.sistemas.ro.gov.br\/\">LINK INSCRI\u00c7\u00c3O<\/a><\/p>\n<p>Fonte: Extra de Rond\u00f4nia<\/p>\n<p>Texto: Marilza Rocha<\/p>\n<p>Fotos: Divulga\u00e7\u00e3o<\/p>\n<p>Secom &#8211; Governo de Rond\u00f4nia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; A Secretaria de Estado da Seguran\u00e7a, Defesa e Cidadania (Sesdec) torna p\u00fablico que a partir de segunda-feira (6) at\u00e9 o dia 27\/11, estar\u00e3o abertas as inscri\u00e7\u00f5es para candidatos interessados em prestar servi\u00e7o volunt\u00e1rio nas Estruturas Administrativas das Unidades Integradas de Seguran\u00e7a P\u00fablica-Unisps, na Capital e no interior do Estado, nas categorias de servi\u00e7o volunt\u00e1rio [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":197433,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-197432","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-classificados-e-concursos"],"_links":{"self":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/197432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/comments?post=197432"}],"version-history":[{"count":0,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/197432\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media\/197433"}],"wp:attachment":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media?parent=197432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/categories?post=197432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/tags?post=197432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}