{"id":204932,"date":"2017-12-26T15:30:31","date_gmt":"2017-12-26T19:30:31","guid":{"rendered":"http:\/\/www.extraderondonia.com.br\/?p=204932"},"modified":"2017-12-26T15:43:59","modified_gmt":"2017-12-26T19:43:59","slug":"mantida-prisao-de-pastora-acusada-de-instigar-tortura","status":"publish","type":"post","link":"https:\/\/www.extraderondonia.com.br\/sistema\/2017\/12\/26\/mantida-prisao-de-pastora-acusada-de-instigar-tortura\/","title":{"rendered":"Mantida pris\u00e3o de pastora acusada de instigar tortura"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><em>Pastora \u00e9 acusada de incitar fiel a praticar tortura contra sua filha menor de idade<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-204933\" src=\"http:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2017\/12\/images-1.jpg\" alt=\"\" width=\"275\" height=\"183\" srcset=\"https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2017\/12\/images-1.jpg 275w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2017\/12\/images-1-120x80.jpg 120w\" sizes=\"auto, (max-width: 275px) 100vw, 275px\" \/>Os desembargadores da 2\u00aa C\u00e2mara Criminal do Tribunal de Justi\u00e7a de Rond\u00f4nia (TJ-RO) mantiveram a pris\u00e3o preventiva da pastora Edinalva Carvalho Nogueira, presa h\u00e1 mais de dois meses pela acusa\u00e7\u00e3o de incitar uma fiel da Igreja Pentecostal de Liberta\u00e7\u00e3o Deus a praticar tortura contra sua filha menor de idade. A igreja fica em Cerejeiras, interior do estado de Rond\u00f4nia.<\/p>\n<p>Ao votar pela manuten\u00e7\u00e3o da pris\u00e3o, a relatora desembargadora Marialva Daldegan Bueno deixa clara a necessidade da segrega\u00e7\u00e3o da acusada, \u201cque demonstra periculosidade incompat\u00edvel com o estado de liberdade ao praticar o crime de tortura contra crian\u00e7a\u201d, al\u00e9m de incentivar publicamente em suas prega\u00e7\u00f5es onde \u00e9 pastora, uma m\u00e3e a bater e a\u00e7oitar a pr\u00f3pria filha.<\/p>\n<p>O caso a que se refere a desembargadora ocorreu em 2016, quando a mission\u00e1ria teria instigado e incentivado uma fiel de nome Juliane L.O a aplicar castigo pessoal contra a filha de oito anos. A crian\u00e7a sofreu constantes surras, mediante viol\u00eancia, causando-lhe intenso sofrimento f\u00edsico e mental. Os castigos aplicados foram ordenados pela acusada com base em \u201cfundamentos b\u00edblicos\u201d.<\/p>\n<p>No relat\u00f3rio ao qual o Rondoniaovivo teve acesso, a desembargadora afirmou em seu relat\u00f3rio: \u201cComo forma de incentivar os fi\u00e9is a baterem nos filhos, declarando que os pais tinham que chegar a vara sem d\u00f3 nos filhos, principalmente nas crian\u00e7as para que crescessem jovens corretos, chegando a afirmar que crian\u00e7a que atrapalha a obra do senhor deve ser eliminada\u201d.<\/p>\n<p>A magistrada finaliza dizendo: \u201cA codenunciada Juliane, em janeiro de 2016, por orienta\u00e7\u00e3o da paciente que era pastora da igreja, retirou a sua filha\/v\u00edtima do lar dos av\u00f3s maternos, onde a menor residia desde os dois anos de idade, e passou a surr\u00e1-la constantemente, inclusive na pr\u00f3pria igreja sob a recomenda\u00e7\u00e3o da paciente, de tal modo que a infante passou a n\u00e3o querer mais residir com a pr\u00f3pria m\u00e3e, ficando com traumas de voltar ao conv\u00edvio da genitora\u201d.<\/p>\n<p>Fonte: Di\u00e1rio da Amaz\u00f4nia<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Pastora \u00e9 acusada de incitar fiel a praticar tortura contra sua filha menor de idade Os desembargadores da 2\u00aa C\u00e2mara Criminal do Tribunal de Justi\u00e7a de Rond\u00f4nia (TJ-RO) mantiveram a pris\u00e3o preventiva da pastora Edinalva Carvalho Nogueira, presa h\u00e1 mais de dois meses pela acusa\u00e7\u00e3o de incitar uma fiel da Igreja Pentecostal de Liberta\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":204933,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-204932","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial"],"_links":{"self":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/204932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/comments?post=204932"}],"version-history":[{"count":0,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/204932\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media\/204933"}],"wp:attachment":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media?parent=204932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/categories?post=204932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/tags?post=204932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}