{"id":210088,"date":"2018-02-03T11:21:24","date_gmt":"2018-02-03T15:21:24","guid":{"rendered":"http:\/\/www.extraderondonia.com.br\/?p=210088"},"modified":"2018-02-05T10:26:40","modified_gmt":"2018-02-05T14:26:40","slug":"homem-e-detido-por-tentativa-de-homicidio-direcao-perigosa-embriaguez-e-desobediencia-apos-avancar-com-veiculo-contra-militar-em-blitz","status":"publish","type":"post","link":"https:\/\/www.extraderondonia.com.br\/sistema\/2018\/02\/03\/homem-e-detido-por-tentativa-de-homicidio-direcao-perigosa-embriaguez-e-desobediencia-apos-avancar-com-veiculo-contra-militar-em-blitz\/","title":{"rendered":"Homem \u00e9 detido por tentativa de homic\u00eddio, dire\u00e7\u00e3o perigosa, embriaguez e desobedi\u00eancia ap\u00f3s avan\u00e7ar com ve\u00edculo contra militar em blitz"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-210092\" src=\"http:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/02\/1517676650206-300x213.png\" alt=\"\" width=\"300\" height=\"213\" srcset=\"https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/02\/1517676650206-300x213.png 300w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/02\/1517676650206-100x70.png 100w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/02\/1517676650206-696x494.png 696w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/02\/1517676650206-592x420.png 592w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/02\/1517676650206-600x426.png 600w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/02\/1517676650206.png 720w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>O fato se deu na madrugada deste s\u00e1bado, 03, durante uma blitz da Lei Seca, realizada na Avenida Paran\u00e1, esquina com a Avenida Dios Bispo de Souza, onde um jovem de 25 anos quase atropelou um policial durante uma fuga.<\/p>\n<p>O jovem, identificado como Douglas Willyans Severo, que conduzia uma caminhonete de cor cinza, trafegava sentido BR-364, e ao visualizar a blitz, deu uma freada brusca, tentando fugir pela Avenida Dios Bispo de Souza, avan\u00e7ando com o ve\u00edculo bruscamente contra um tenente da Pol\u00edcia Militar que realizava a sinaliza\u00e7\u00e3o do desvio de fluxo da via.<\/p>\n<p>Para n\u00e3o ser atingido, o militar teve que fazer uso de habilidades evasivas, esquivando-se do ve\u00edculo, devido o motorista, em nenhum momento ter reduzido a acelera\u00e7\u00e3o, mesmo avistando o policial lhe dando ordens de parada.<\/p>\n<p>Ap\u00f3s quase atingir o tenente, o motorista empreendeu fuga em alta velocidade, sendo acompanhado por uma guarni\u00e7\u00e3o, que avistou o momento em que o infrator entrou rapidamente na garagem de uma resid\u00eancia, localizada na Rua Joaquim Nabuco.<\/p>\n<p>Diante da nega\u00e7\u00e3o do agente em abrir o port\u00e3o, se trancando na casa, os militares foram obrigados a romper os fios da cerca el\u00e9trica e arrombar a porta do im\u00f3vel para realizar a pris\u00e3o do infrator.<\/p>\n<p>Mesmo ap\u00f3s a entrada dos policiais na resid\u00eancia solicitando que o jovem colocasse as m\u00e3os na cabe\u00e7a, este n\u00e3o obedeceu, reagindo contra a guarni\u00e7\u00e3o com socos e chutes, sendo necess\u00e1rio o uso moderado da for\u00e7a para cont\u00ea-lo.<\/p>\n<p>Segundo o registro da ocorr\u00eancia, o agente apresentava vis\u00edveis sinais de embriaguez e foi levado novamente at\u00e9 o local da blitz para que fossem confeccionados os documentos de tr\u00e2nsito necess\u00e1rios, onde tamb\u00e9m compareceu um advogado acionado pelos familiares do infrator, que acompanhou todos os tramites, inclusive a condu\u00e7\u00e3o do mesmo at\u00e9 a Unidade Integrada de Seguran\u00e7a P\u00fablica (Unisp) para o registro do flagrante.<\/p>\n<p>O ve\u00edculo utilizado na pr\u00e1tica dos crimes foi recolhido ao p\u00e1tio da CIRETRAN.<\/p>\n<p>&nbsp;<\/p>\n<p>Texto: Extra de Rond\u00f4nia<\/p>\n<p>Foto:\u00a0Extra de Rond\u00f4nia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; O fato se deu na madrugada deste s\u00e1bado, 03, durante uma blitz da Lei Seca, realizada na Avenida Paran\u00e1, esquina com a Avenida Dios Bispo de Souza, onde um jovem de 25 anos quase atropelou um policial durante uma fuga. O jovem, identificado como Douglas Willyans Severo, que conduzia uma caminhonete de cor cinza, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":210092,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-210088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial"],"_links":{"self":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/210088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/comments?post=210088"}],"version-history":[{"count":0,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/210088\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media\/210092"}],"wp:attachment":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media?parent=210088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/categories?post=210088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/tags?post=210088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}