{"id":217152,"date":"2018-04-03T09:47:28","date_gmt":"2018-04-03T13:47:28","guid":{"rendered":"http:\/\/www.extraderondonia.com.br\/?p=217152"},"modified":"2018-04-04T10:33:24","modified_gmt":"2018-04-04T14:33:24","slug":"servidores-da-educacao-realizam-movimento-reivindicatorio-na-praca-nossa-senhora-aparecida-de-vilhena","status":"publish","type":"post","link":"https:\/\/www.extraderondonia.com.br\/sistema\/2018\/04\/03\/servidores-da-educacao-realizam-movimento-reivindicatorio-na-praca-nossa-senhora-aparecida-de-vilhena\/","title":{"rendered":"Servidores da educa\u00e7\u00e3o realizam movimento reivindicat\u00f3rio na Pra\u00e7a Nossa Senhora Aparecida de Vilhena"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-217153\" src=\"http:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/DSC_0033-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/DSC_0033-300x199.jpg 300w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/DSC_0033-632x420.jpg 632w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/DSC_0033-600x398.jpg 600w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/DSC_0033-120x80.jpg 120w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/DSC_0033.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Na manh\u00e3 desta ter\u00e7a-feira, 03, v\u00e1rios servidores da educa\u00e7\u00e3o se reuniram na Pra\u00e7a Nossa Senhora Aparecida de Vilhena para reivindicarem aten\u00e7\u00e3o \u00e0s propostas das metas de valoriza\u00e7\u00e3o da classe educacional. Vale pontuar que tais reivindica\u00e7\u00f5es tem gerado uma s\u00e9rie de protestos e uma greve que se estende a mais de 40 dias.<\/p>\n<p>De acordo com a diretora da regional Cone Sul Sintero, Osnier Gomes Pereira Machado, \u201ceste tipo de a\u00e7\u00e3o \u00e9 decidida em assembleia. Como tivemos o retorno j\u00e1 na segunda-feira, realizamos os encaminhamentos e deliberamos as a\u00e7\u00f5es a serem realizadas durante toda a semana. At\u00e9 porque n\u00e3o \u00e9 interessante que fiquemos apenas na sede do Sintero, as pessoas precisam ver que continuamos aqui na luta por nossos direitos e que o governo n\u00e3o se articulou para atender nossa pauta reivindicat\u00f3ria\u201d.<\/p>\n<p>Cabe destacar que os servidores est\u00e3o reivindicando a aprova\u00e7\u00e3o do plano estadual de educa\u00e7\u00e3o, em especial as metas 17, 18 e 19 que consistem em:<\/p>\n<p>\u2013 Valorizar os profissionais do magist\u00e9rio das redes p\u00fablicas da educa\u00e7\u00e3o b\u00e1sica, a fim de equiparar gradualmente, a partir da vig\u00eancia deste plano, ao rendimento m\u00e9dio dos demais profissionais com escolaridade equivalente.<\/p>\n<p>\u2013 Garantir, no prazo de dois anos, a elabora\u00e7\u00e3o e implanta\u00e7\u00e3o de planos de carreira para os profissionais da Educa\u00e7\u00e3o B\u00e1sica de todos os sistemas de ensino e, para o Plano de Carreira dos Profissionais da Educa\u00e7\u00e3o B\u00e1sica p\u00fablica, tomar como refer\u00eancia o Piso Salarial Nacional Profissional, definido em lei federal, nos termos inciso VIII do art. 206 da Constitui\u00e7\u00e3o Federal.<\/p>\n<p>\u2013 Ampliar o investimento p\u00fablico em educa\u00e7\u00e3o p\u00fablica de forma a garantir investimento de no m\u00ednimo 35% com recursos do tesouro estadual para complementa\u00e7\u00e3o do FUNDEB, com amplia\u00e7\u00e3o gradativa de 1% ao ano durante o per\u00edodo de vig\u00eancia do PEE.<\/p>\n<p>Sobre o cronograma de a\u00e7\u00f5es a representante enfatiza que \u201cinicia hoje com a concentra\u00e7\u00e3o na Pra\u00e7a Nossa Senhora Aparecida; amanh\u00e3 na Pra\u00e7a do Mensageiro e com a realiza\u00e7\u00e3o de reuni\u00e3o diretiva da classe em Porto velho; na quinta-feira na Pra\u00e7a do Shopping e na sexta-feira haver\u00e1 uma concentra\u00e7\u00e3o de servi\u00e7o p\u00fablico atrav\u00e9s da campanha de doa\u00e7\u00e3o de sangue junto ao Hemocentro\u201d.<\/p>\n<p>Em rela\u00e7\u00e3o \u00e0 paralisa\u00e7\u00e3o da BR-364, Osnier conta que \u201co governador marcou uma audi\u00eancia com o deputado estadual, Luizinho Goebel (PV), para tratar do assunto, mas Conf\u00facio o enrolou e n\u00e3o o atendeu. Devido a isso nada foi acordado. Neste per\u00edodo desocupamos a BR, at\u00e9 porque a Policia Rodovi\u00e1ria Federal(PRF) n\u00e3o tinha como manter nossa seguran\u00e7a durante a noite\u201d.<\/p>\n<p>Osnier esclarece que diante da situa\u00e7\u00e3o ainda n\u00e3o se tem previs\u00e3o de quando cessar\u00e1 a greve, at\u00e9 porque o governo nada fez para negociar com os servidores. \u201cGostaria de destacar que nosso movimento \u00e9 legitimo e necess\u00e1rio, j\u00e1 temos cerca de 85% dos trabalhadores de todo o Estado apoiando a causa e lutando pela valoriza\u00e7\u00e3o de nossa classe\u201d, finalizou a representante.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-217154\" src=\"http:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/DSC_0027-600x398.jpg\" alt=\"\" width=\"600\" height=\"398\" srcset=\"https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/DSC_0027-600x398.jpg 600w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/DSC_0027-300x199.jpg 300w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/DSC_0027-120x80.jpg 120w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/DSC_0027.jpg 640w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-217155\" src=\"http:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/DSC_0032-600x398.jpg\" alt=\"\" width=\"600\" height=\"398\" srcset=\"https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/DSC_0032-600x398.jpg 600w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/DSC_0032-300x199.jpg 300w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/DSC_0032-120x80.jpg 120w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/DSC_0032.jpg 640w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-217156\" src=\"http:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/DSC_0006-600x398.jpg\" alt=\"\" width=\"600\" height=\"398\" srcset=\"https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/DSC_0006-600x398.jpg 600w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/DSC_0006-300x199.jpg 300w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/DSC_0006-120x80.jpg 120w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/DSC_0006.jpg 640w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Texto: Extra de Rond\u00f4nia<\/p>\n<p>Fotos: Extra de Rond\u00f4nia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Na manh\u00e3 desta ter\u00e7a-feira, 03, v\u00e1rios servidores da educa\u00e7\u00e3o se reuniram na Pra\u00e7a Nossa Senhora Aparecida de Vilhena para reivindicarem aten\u00e7\u00e3o \u00e0s propostas das metas de valoriza\u00e7\u00e3o da classe educacional. Vale pontuar que tais reivindica\u00e7\u00f5es tem gerado uma s\u00e9rie de protestos e uma greve que se estende a mais de 40 dias. De acordo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":217153,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-217152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/217152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/comments?post=217152"}],"version-history":[{"count":0,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/217152\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media\/217153"}],"wp:attachment":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media?parent=217152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/categories?post=217152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/tags?post=217152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}