{"id":217169,"date":"2018-04-03T10:27:30","date_gmt":"2018-04-03T14:27:30","guid":{"rendered":"http:\/\/www.extraderondonia.com.br\/?p=217169"},"modified":"2018-04-04T10:32:50","modified_gmt":"2018-04-04T14:32:50","slug":"condutor-de-picape-invade-preferencial-e-deixa-motociclista-ferida","status":"publish","type":"post","link":"https:\/\/www.extraderondonia.com.br\/sistema\/2018\/04\/03\/condutor-de-picape-invade-preferencial-e-deixa-motociclista-ferida\/","title":{"rendered":"Condutor de picape invade preferencial e deixa motociclista ferida"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-217170\" src=\"http:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/cf1a88f1-3817-49b9-bfd0-183dca5e1eda-300x198.jpg\" alt=\"\" width=\"300\" height=\"198\" srcset=\"https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/cf1a88f1-3817-49b9-bfd0-183dca5e1eda-300x198.jpg 300w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/cf1a88f1-3817-49b9-bfd0-183dca5e1eda-637x420.jpg 637w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/cf1a88f1-3817-49b9-bfd0-183dca5e1eda-600x395.jpg 600w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/cf1a88f1-3817-49b9-bfd0-183dca5e1eda-120x80.jpg 120w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/cf1a88f1-3817-49b9-bfd0-183dca5e1eda.jpg 663w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>O acidente ocorreu por volta das 09h30 desta ter\u00e7a-feira, 03, no cruzamento das Avenidas Tancredo Neves com Presidente Nasser, no Jardim Am\u00e9rica em Vilhena.<\/p>\n<p>Segundo relatos do condutor de uma picape Strada, ele seguia pela Tancredo Neves, sentido Prefeitura Municipal, quando avan\u00e7ou a preferencial e acabou atingindo a condutora de uma motoneta Honda Biz, que seguia pela Presidente Nasser, sentido Perimetral.<\/p>\n<p>Na queda, a mulher sofreu escoria\u00e7\u00f5es em uma das pernas e foi conduzida ao hospital por uma Unidade de Resgate do Corpo de Bombeiros.<\/p>\n<p>Os envolvidos entraram em acordo ainda no local e o condutor da picape removeu a motocicleta da v\u00edtima para manuten\u00e7\u00e3o, n\u00e3o sendo necess\u00e1ria a presen\u00e7a da per\u00edcia t\u00e9cnica.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-217171\" src=\"http:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/6bc8114c-ca7f-44d9-9ebd-a45c78c78589-600x337.jpg\" alt=\"\" width=\"600\" height=\"337\" srcset=\"https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/6bc8114c-ca7f-44d9-9ebd-a45c78c78589-600x337.jpg 600w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/6bc8114c-ca7f-44d9-9ebd-a45c78c78589-300x168.jpg 300w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/6bc8114c-ca7f-44d9-9ebd-a45c78c78589-768x431.jpg 768w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/6bc8114c-ca7f-44d9-9ebd-a45c78c78589-800x449.jpg 800w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/6bc8114c-ca7f-44d9-9ebd-a45c78c78589-140x80.jpg 140w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/04\/6bc8114c-ca7f-44d9-9ebd-a45c78c78589.jpg 1040w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Texto: Extra de Rond\u00f4nia<\/p>\n<p>Fotos: Extra de Rond\u00f4nia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; O acidente ocorreu por volta das 09h30 desta ter\u00e7a-feira, 03, no cruzamento das Avenidas Tancredo Neves com Presidente Nasser, no Jardim Am\u00e9rica em Vilhena. Segundo relatos do condutor de uma picape Strada, ele seguia pela Tancredo Neves, sentido Prefeitura Municipal, quando avan\u00e7ou a preferencial e acabou atingindo a condutora de uma motoneta Honda Biz, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":217170,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-217169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial"],"_links":{"self":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/217169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/comments?post=217169"}],"version-history":[{"count":0,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/217169\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media\/217170"}],"wp:attachment":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media?parent=217169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/categories?post=217169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/tags?post=217169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}