{"id":222713,"date":"2018-05-18T15:01:16","date_gmt":"2018-05-18T19:01:16","guid":{"rendered":"http:\/\/www.extraderondonia.com.br\/?p=222713"},"modified":"2018-05-21T14:17:44","modified_gmt":"2018-05-21T18:17:44","slug":"homem-e-detido-por-posse-de-arma-de-fogo-e-desmatamento-ilegal-em-distrito-de-corumbiara","status":"publish","type":"post","link":"https:\/\/www.extraderondonia.com.br\/sistema\/2018\/05\/18\/homem-e-detido-por-posse-de-arma-de-fogo-e-desmatamento-ilegal-em-distrito-de-corumbiara\/","title":{"rendered":"Homem \u00e9 detido por posse de arma de fogo e desmatamento ilegal em distrito de Corumbiara"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-222727\" src=\"http:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/05\/desmatamento-foto-giro2-300x224.jpg\" alt=\"\" width=\"300\" height=\"224\" srcset=\"https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/05\/desmatamento-foto-giro2-300x224.jpg 300w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/05\/desmatamento-foto-giro2-80x60.jpg 80w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/05\/desmatamento-foto-giro2-265x198.jpg 265w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/05\/desmatamento-foto-giro2-294x221.jpg 294w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2018\/05\/desmatamento-foto-giro2.jpg 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>O fato foi registrado na tarde de quinta-feira, 17, na delegacia de Pol\u00edcia Civil do munic\u00edpio Cerejeiras.<\/p>\n<p>Sildevan Beltr\u00e3o Ramos, de 35 anos, foi detido Pol\u00edcia Militar Ambiental (PMA) em conjunto com a Secretaria de Estado do Desenvolvimento Ambiental (SEDAM) durante fiscaliza\u00e7\u00e3o no Assentamento Maranata II \u2013 Alto Guarajus, distrito do munic\u00edpio de Corumbiara.<\/p>\n<p>De acordo com boletim de ocorr\u00eancia, no local a pol\u00edcia encontrou desmatamento, extra\u00e7\u00e3o ilegal de madeira, uso de fogo em floresta, madeiras serradas, tr\u00eas motosserras, uma espingarda calibre 28 e muni\u00e7\u00f5es.<\/p>\n<p>Diante dos fatos, o homem foi levado para a delegacia de pol\u00edcia, onde dever\u00e1 responder por crime ambiental.<\/p>\n<p>Texto: Extra de Rond\u00f4nia<\/p>\n<p>Foto: Ilustra\u00e7\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; O fato foi registrado na tarde de quinta-feira, 17, na delegacia de Pol\u00edcia Civil do munic\u00edpio Cerejeiras. Sildevan Beltr\u00e3o Ramos, de 35 anos, foi detido Pol\u00edcia Militar Ambiental (PMA) em conjunto com a Secretaria de Estado do Desenvolvimento Ambiental (SEDAM) durante fiscaliza\u00e7\u00e3o no Assentamento Maranata II \u2013 Alto Guarajus, distrito do munic\u00edpio de Corumbiara. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":222727,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-222713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conesul"],"_links":{"self":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/222713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/comments?post=222713"}],"version-history":[{"count":0,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/222713\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media\/222727"}],"wp:attachment":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media?parent=222713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/categories?post=222713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/tags?post=222713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}