{"id":248246,"date":"2019-01-02T12:09:26","date_gmt":"2019-01-02T16:09:26","guid":{"rendered":"http:\/\/www.extraderondonia.com.br\/?p=248246"},"modified":"2019-01-03T15:01:39","modified_gmt":"2019-01-03T19:01:39","slug":"sem-dialogo-prefeito-assinala-por-embate-juridico-para-nao-acatar-decisao-de-vereadores-que-rejeitaram-veto-ao-iptu","status":"publish","type":"post","link":"https:\/\/www.extraderondonia.com.br\/sistema\/2019\/01\/02\/sem-dialogo-prefeito-assinala-por-embate-juridico-para-nao-acatar-decisao-de-vereadores-que-rejeitaram-veto-ao-iptu\/","title":{"rendered":"SEM DI\u00c1LOGO: prefeito assinala por embate jur\u00eddico para n\u00e3o acatar decis\u00e3o de vereadores que rejeitaram veto ao IPTU"},"content":{"rendered":"<p><a href=\"http:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2019\/01\/japa-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-248247\" src=\"http:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2019\/01\/japa-1-300x216.jpg\" alt=\"\" width=\"300\" height=\"216\" srcset=\"https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2019\/01\/japa-1-300x216.jpg 300w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2019\/01\/japa-1.jpg 354w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Ao que tudo indica, o prefeito de Vilhena, Eduardo Japon\u00eas (PV), deve decidir pelo embate jur\u00eddico para n\u00e3o acatar a decis\u00e3o da maioria dos vereadores referente ao Imposto Predial Territorial Urbano (IPTU) semana passada.<\/p>\n<p>Oito dos doze atuais vereadores se reuniram semana passada e \u201cderrubaram\u201d o veto parcial relativo \u00e0 Emenda Modificativa apresentada pelo vereador Rafael Maziero (PSDB), prev\u00ea que \u201cas al\u00edquotas progressivas n\u00e3o ser\u00e3o aplicadas caso o propriet\u00e1rio possua um \u00fanico im\u00f3vel\u201d. Relembre <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/12\/29\/iptu-vereadores-derrubam-veto-de-prefeito-e-aliquota-progressiva-nao-sera-aplicada-a-quem-possuir-um-unico-imovel\/\">AQUI<\/a><\/p>\n<p>De acordo com informa\u00e7\u00f5es extraoficiais, a Procuradoria Geral do Munic\u00edpio (PGM) assinalou a possibilidade de emitir parecer para seguir o entendimento original que vetou a proposta do parlamentar tucano alegando inconstitucionalidade da mat\u00e9ria.<\/p>\n<p>Caso Japon\u00eas decida por manter seu posicionamento, a situa\u00e7\u00e3o deve parar nos tribunais.<\/p>\n<p>O <strong><em>Extra de Rond\u00f4nia<\/em><\/strong> entrou em contato com a assessoria da prefeitura e aguarda nota a respeito do assunto.<\/p>\n<p>Um vereador ouvido pelo site garante que o entendimento da assessoria jur\u00eddica do Poder Legislativo tem embasamento legal e que recorrer\u00e1 \u00e0 justi\u00e7a caso o prefeito n\u00e3o respeite a decis\u00e3o soberana do plen\u00e1rio.<\/p>\n<p>O veto do prefeito, contudo, contraria o discurso de que houve tal \u201camplo debate\u201d com os parlamentares. Relembre\u00a0<a style=\"font-weight: inherit; font-style: inherit;\" href=\"http:\/\/www.extraderondonia.com.br\/2018\/12\/24\/veto-contraria-discurso-de-japones-e-revela-falta-de-dialogo-com-vereadores-no-ajuste-do-iptu\/\">AQUI<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Texto: Extra de Rond\u00f4nia<\/p>\n<p>Foto: Extra de Rond\u00f4nia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ao que tudo indica, o prefeito de Vilhena, Eduardo Japon\u00eas (PV), deve decidir pelo embate jur\u00eddico para n\u00e3o acatar a decis\u00e3o da maioria dos vereadores referente ao Imposto Predial Territorial Urbano (IPTU) semana passada. Oito dos doze atuais vereadores se reuniram semana passada e \u201cderrubaram\u201d o veto parcial relativo \u00e0 Emenda Modificativa apresentada pelo vereador [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":248247,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-248246","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/248246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/comments?post=248246"}],"version-history":[{"count":0,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/248246\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media\/248247"}],"wp:attachment":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media?parent=248246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/categories?post=248246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/tags?post=248246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}