{"id":248261,"date":"2019-01-03T11:18:12","date_gmt":"2019-01-03T15:18:12","guid":{"rendered":"http:\/\/www.extraderondonia.com.br\/?p=248261"},"modified":"2019-01-11T11:31:36","modified_gmt":"2019-01-11T15:31:36","slug":"estatisticas-apontam-meses-mais-sangrentos-de-2018-em-vilhena-e-chupinguaia","status":"publish","type":"post","link":"https:\/\/www.extraderondonia.com.br\/sistema\/2019\/01\/03\/estatisticas-apontam-meses-mais-sangrentos-de-2018-em-vilhena-e-chupinguaia\/","title":{"rendered":"Estat\u00edsticas apontam meses mais sangrentos de 2018 em Vilhena e Chupinguaia"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-248272\" src=\"http:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2019\/01\/1537985410-5babcc9c2d117_capa_homicidio-300x180.jpg\" alt=\"\" width=\"300\" height=\"180\" srcset=\"https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2019\/01\/1537985410-5babcc9c2d117_capa_homicidio-300x180.jpg 300w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2019\/01\/1537985410-5babcc9c2d117_capa_homicidio-696x418.jpg 696w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2019\/01\/1537985410-5babcc9c2d117_capa_homicidio-1068x641.jpg 1068w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2019\/01\/1537985410-5babcc9c2d117_capa_homicidio-700x420.jpg 700w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2019\/01\/1537985410-5babcc9c2d117_capa_homicidio-1920x1152.jpg 1920w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2019\/01\/1537985410-5babcc9c2d117_capa_homicidio-768x461.jpg 768w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2019\/01\/1537985410-5babcc9c2d117_capa_homicidio-600x360.jpg 600w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2019\/01\/1537985410-5babcc9c2d117_capa_homicidio-800x480.jpg 800w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2019\/01\/1537985410-5babcc9c2d117_capa_homicidio-200x120.jpg 200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>O <strong>Extra de Rond\u00f4nia<\/strong> teve acesso aos registros da Delegacia de Homic\u00eddios e Prote\u00e7\u00e3o a Pessoas (DHPP) de Vilhena e constatou que o m\u00eas de maio, do ano de 2018, foi considerado o mais sangrento, pois dos 51 assassinatos consumados, oito ocorreram nele, seguido dos meses de janeiro, julho e setembro, que registraram sete casos cada.<\/p>\n<p>Dos 51 homic\u00eddios consumados, dos quais dois foram duplos e um latroc\u00ednio (roubo seguido de morte), 10 ocorreram no munic\u00edpio de Chupinguaia e seus distritos.<\/p>\n<p>Al\u00e9m da brutalidade usada pelos agentes, que dos 51, 28 fizeram uso de arma com tiros desferidos a queima roupa, 15 usaram facas, sete se muniram de peda\u00e7os de madeira ou pedras e um fez uso de fogo, o que tamb\u00e9m chama a aten\u00e7\u00e3o \u00e9 o aumento dos crimes cometidos na zona rural, que ao todo somaram 15 casos.<\/p>\n<p>Como j\u00e1 foi informado pelo site, em uma mat\u00e9ria divulgada na virada de ano (Reveja <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/12\/31\/dhpp-registra-em-2018-treze-homicidios-a-mais-que-em-2017\/\">AQUI<\/a>), apenas cinco v\u00edtimas eram mulheres, sendo duas delas, dos dois casos de duplo homic\u00eddio registrados, e ao contr\u00e1rio do ano anterior, em que a maioria das v\u00edtimas eram jovens e adolescentes, em 2018, grande parte possu\u00edam mais de 30 anos.<\/p>\n<p>Apenas o primeiro assassinato registrado no ano, salvo os ainda n\u00e3o desvendados, foi cometido por uma mulher, dois por menores de idade, um por motivo passional e 21, por acerto de contas.<\/p>\n<p>Al\u00e9m dos casos de homic\u00eddios consumados, dos quais 24 j\u00e1 foram elucidados, 13 est\u00e3o com investiga\u00e7\u00f5es avan\u00e7as e 14 ainda n\u00e3o foram levantadas nenhum tipo de informa\u00e7\u00e3o plaus\u00edvel, cerca de 37 inqu\u00e9ritos tamb\u00e9m foram instaurados para investigar os homic\u00eddios tentados, ocorridos nos dois munic\u00edpios e seus distritos.<\/p>\n<p>Confira abaixo os n\u00fameros de homic\u00eddios cometidos em cada m\u00eas do ano e suas localidades:<\/p>\n<p><strong>JANEIRO<\/strong><\/p>\n<p>1\u00ba\u00a0 <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/01\/01\/chupinguaia-mulher-confessa-ter-matado-jovem-a-golpes-de-gargalo-de-garrafa\/\">Chupinguaia<\/a><\/p>\n<p>2\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/01\/01\/primeiro-homicidio-de-2018-em-vilhena-e-registrado-no-cristo-rei\/\">Vilhena<\/a><\/p>\n<p>3\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/01\/03\/vilhena-homem-baleado-na-cabeca-morre-em-uti-de-cacoal\/\">Vilhena<\/a><\/p>\n<p>4\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/01\/06\/jovem-e-assassinado-a-tiros-em-chupinguaia\/\">Chupinguaia<\/a><\/p>\n<p>5\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/01\/11\/morre-homem-esfaqueado-pelo-proprio-sobrinho-por-ciumes\/\">Vilhena<\/a><\/p>\n<p>6\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/01\/12\/identificado-corpo-encontrado-a-cerca-de-66-km-de-vilhena-homem-foi-morto-a-golpes-de-machado\/\">Vilhena (Latroc\u00ednio) (zona rural)<\/a><\/p>\n<p>7\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/01\/21\/homem-e-morto-a-tiros-no-cristo-rei-ele-ja-havia-sobrevivido-ha-tres-tentativas\/\">Vilhena<\/a><\/p>\n<p><strong>FEVEREIRO<\/strong><\/p>\n<p>N\u00e3o houve registros<\/p>\n<p><strong>MAR\u00c7O <\/strong><\/p>\n<p>8\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/03\/27\/chupinguaia-homem-e-morto-a-facadas-por-colega-de-trabalho-da-esposa\/\">Chupinguaia<\/a><\/p>\n<p><strong>ABRIL<\/strong><\/p>\n<p>9\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/04\/28\/servidor-publico-e-morto-enquanto-tomava-cerveja-e-ouvia-musica-em-bar-no-bela-vista\/\">Vilhena<\/a><\/p>\n<p><strong>MAIO<\/strong><\/p>\n<p>10\u00ba Vilhena<\/p>\n<p>11\u00ba Vilhena<\/p>\n<p>12\u00ba Vilhena (zona rural)<\/p>\n<p>13\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/05\/20\/mais-um-assassinato-e-registrado-neste-domingo-em-vilhena-homem-foi-morto-a-golpes-de-tijolo\/\">Vilhena<\/a><\/p>\n<p>14\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/05\/26\/policial-militar-e-morto-a-golpes-de-foice-em-distrito-de-chupinguaia-cunhado-e-suspeito-do-crime\/\">Chupinguaia (zona rural)<\/a><\/p>\n<p>15\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/05\/27\/mecanico-e-executado-com-tres-tiros-na-cabeca-no-bairro-cristo-rei\/\">Vilhena<\/a><\/p>\n<p>16\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/05\/20\/cantor-e-assassinado-em-cima-de-palco-ciumes-teria-sido-a-causa-do-homicidio\/\">Vilhena (zona rural)<\/a><\/p>\n<p>17\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/05\/30\/caminhoneiro-morre-apos-ser-atingido-por-pedra-lancada-por-manifestante-em-vilhena\/\">Vilhena<\/a><\/p>\n<p><strong>JUNHO<\/strong><\/p>\n<p>18\u00ba Vilhena<\/p>\n<p>19\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/06\/19\/caseiro-e-encontrado-morto-com-tiro-de-espingarda-na-cabeca\/\">Vilhena (zona rural)<\/a><\/p>\n<p><strong>JULHO<\/strong><\/p>\n<p>20\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/07\/01\/vigia-de-posto-de-combustivel-e-executado-a-tiros-no-centro-de-vilhena\/\">Vilhena<\/a><\/p>\n<p>21\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/07\/08\/chupinguaia-homem-confessa-ao-pai-que-matou-ex-mulher-e-pede-que-ele-cuide-de-sua-filha-antes-de-fugir\/\">Chupinguaia (mulher)<\/a><\/p>\n<p>22\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/07\/10\/homem-morto-com-tiro-no-peito-e-identificado-e-estava-em-acampamento-de-sem-terra-na-area-rural-de-vilhena\/\">Vilhena (zona rural)<\/a><\/p>\n<p>23\u00ba Vilhena<\/p>\n<p>24\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/07\/15\/chacareiro-e-assassinado-a-tiros-na-area-rural-de-vilhena-antes-de-morrer-ligou-para-filha-e-falou-o-nome-do-suspeito\/\">Vilhena (zona rural)<\/a><\/p>\n<p>25\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/07\/24\/em-vilhena-mulher-e-assassinada-a-facadas-e-casa-e-incendiada\/\">Vilhena (mulher)<\/a><\/p>\n<p>26\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/07\/11\/funcionario-da-semosp-e-alvejado-com-tiro-nas-costas-no-jardim-eldorado\/\">Vilhena<\/a><\/p>\n<p><strong>AGOSTO<\/strong><\/p>\n<p>27\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/08\/06\/homem-esfaqueado-por-irmao-morre-por-complicacoes-apos-receber-alta\/\">Vilhena (zona rural)<\/a><\/p>\n<p>28\u00ba Vilhena<\/p>\n<p><strong>SETEMBRO<\/strong><\/p>\n<p>29\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/09\/07\/homem-e-morto-a-tiros-na-porta-de-casa-no-bairro-alphaville-em-vilhena\/\">Vilhena<\/a><\/p>\n<p>30\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/09\/10\/homem-e-assassinado-com-varios-tiros-de-pistola-no-jardim-eldorado-em-vilhena\/\">Vilhena<\/a><\/p>\n<p>31\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/09\/15\/um-dos-primeiros-chapas-de-vilhena-e-morto-a-pedrada-no-local-onde-trabalhou-por-muitos-anos\/\">Vilhena<\/a><\/p>\n<p>32\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/09\/26\/morre-na-uti-homem-baleado-no-conjunto-alvorada-em-vilhena\/\">Vilhena<\/a><\/p>\n<p>33\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/09\/27\/homem-que-teve-corpo-queimado-por-companheiro-morre-na-uti-do-hrv\/\">Vilhena<\/a><\/p>\n<p>34\u00ba Vilhena<\/p>\n<p>35\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/09\/30\/jovem-e-perseguido-e-morto-a-tiros-no-jardim-primavera-em-vilhena\/\">Vilhena<\/a><\/p>\n<p><strong>OUTUBRO<\/strong><\/p>\n<p>36\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/10\/11\/homem-e-assassinado-com-cinco-tiros-na-cabeca-na-frente-de-amigo-no-embratel\/\">Vilhena<\/a><\/p>\n<p>37\u00ba e 38\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/10\/22\/identificado-casal-de-idosos-assassinado-com-resquicios-de-crueldade-no-guapore\/\">Chupinguaia (duplo homic\u00eddio) (zona rural) \u00a0<\/a><\/p>\n<p>39\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/10\/27\/apenado-e-executado-a-tiros-no-alto-dos-parecis\/\">Vilhena<\/a><\/p>\n<p>40\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/10\/27\/homem-e-encontrado-morto-com-sinais-de-execucao-em-chupinguaia\/\">Chupinguaia (zona rural)<\/a><\/p>\n<p>41\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/10\/27\/homem-e-assassinado-com-tres-tiros-no-centro-de-vilhena\/\">Vilhena<\/a><\/p>\n<p><strong>NOVEMBRO<\/strong><\/p>\n<p>42\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/11\/03\/identificado-homem-que-foi-encontrado-morto-dentro-de-casa-no-jardim-primavera\/\">Vilhena<\/a><\/p>\n<p>43\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/11\/13\/homem-e-assassinado-com-tres-tiros-na-cabeca-ao-lado-da-namorada-no-bairro-vila-operaria-em-vilhena\/\">Vilhena<\/a><\/p>\n<p>44\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/11\/25\/homem-e-assassinado-a-golpes-de-tijolo-em-vilhena\/\">Vilhena<\/a><\/p>\n<p>45\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/11\/25\/vilhena-homem-agredido-em-fazenda-morre-na-uti-de-cacoal\/\">Vilhena (zona rural)<\/a><\/p>\n<p><strong>DEZEMBRO<\/strong><\/p>\n<p>46\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/12\/12\/homem-e-morto-com-tiro-de-cartucheira-em-novo-plano-autor-alega-disparo-acidental\/\">Chupinguaia (zona rural)<\/a><\/p>\n<p>47\u00ba e 48 \u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/12\/13\/casal-e-assassinado-a-tiros-no-bela-vista-ex-marido-seria-o-principal-suspeito\/\">Vilhena (duplo homic\u00eddio)<\/a><\/p>\n<p>49\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/12\/18\/identificado-corpo-encontrado-no-setor-chacareiro-de-vilhena\/\">Vilhena (zona rural)<\/a><\/p>\n<p>50\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/12\/24\/corpo-de-adolescente-e-encontrado-proximo-a-torre-da-embratel-em-vilhena\/\">Vilhena (zona rural)<\/a><\/p>\n<p>51\u00ba <a href=\"http:\/\/www.extraderondonia.com.br\/2018\/12\/27\/identificado-corpo-encontrado-na-area-rural-de-chupinguaia\/\">Chupinguaia (zona rural)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; O Extra de Rond\u00f4nia teve acesso aos registros da Delegacia de Homic\u00eddios e Prote\u00e7\u00e3o a Pessoas (DHPP) de Vilhena e constatou que o m\u00eas de maio, do ano de 2018, foi considerado o mais sangrento, pois dos 51 assassinatos consumados, oito ocorreram nele, seguido dos meses de janeiro, julho e setembro, que registraram sete [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":248272,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-248261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial"],"_links":{"self":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/248261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/comments?post=248261"}],"version-history":[{"count":0,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/248261\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media\/248272"}],"wp:attachment":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media?parent=248261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/categories?post=248261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/tags?post=248261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}