{"id":307346,"date":"2020-07-03T16:50:50","date_gmt":"2020-07-03T20:50:50","guid":{"rendered":"https:\/\/www.extraderondonia.com.br\/?p=307346"},"modified":"2020-07-05T16:21:38","modified_gmt":"2020-07-05T20:21:38","slug":"videos-prefeito-anuncia-construcao-de-ponte-e-agradece-luizinho-por-120-metros-de-tubo-armico-em-colorado","status":"publish","type":"post","link":"https:\/\/www.extraderondonia.com.br\/sistema\/2020\/07\/03\/videos-prefeito-anuncia-construcao-de-ponte-e-agradece-luizinho-por-120-metros-de-tubo-armico-em-colorado\/","title":{"rendered":"V\u00cdDEOS: prefeito anuncia constru\u00e7\u00e3o de ponte e agradece Luizinho por 120 metros de tubo armico em Colorado"},"content":{"rendered":"<figure id=\"attachment_307347\" aria-describedby=\"caption-attachment-307347\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2020\/07\/PRE-COLORADO.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-307347\" src=\"https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2020\/07\/PRE-COLORADO-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2020\/07\/PRE-COLORADO-300x192.jpg 300w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2020\/07\/PRE-COLORADO-600x384.jpg 600w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2020\/07\/PRE-COLORADO.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-307347\" class=\"wp-caption-text\"><br \/>Prefeito com servidores da Secretaria Municipal de Infraestrutura \/ Foto: Extra de Rond\u00f4nia<\/figcaption><\/figure>\n<p>Em um v\u00eddeo de pouco mais de 1 minutos, o prefeito de Colorado do Oeste, Jos\u00e9 Ribamar, agradeceu o deputado estadual Luizinho Goebel pela emenda que destinou para a aquisi\u00e7\u00e3o de 120 metros de tubo armico.<\/p>\n<p>O an\u00fancio aconteceu na \u00faltima quarta-feira, 1\u00ba de julho, n\u00e3o p\u00e1tio da secretaria municipal de infraestrutura, com gestores da referida pasta.<\/p>\n<p>\u201cUm trabalho permanente desenvolvido pela Secretaria Municipal de Infraestrutura para a promo\u00e7\u00e3o da melhoria das estradas vicinais e do Desenvolvimento Rural do nosso munic\u00edpio. Externamos nossos agradecimentos ao deputado estadual Luizinho Goebel pela parceria e recursos destinados ao munic\u00edpio\u201d, ressaltou.<\/p>\n<p>Em outro v\u00eddeo, o mandat\u00e1rio municipal anuncia a constru\u00e7\u00e3o de uma ponte de madeira, na Linha Zero 1, entre a 2\u00ba e 3\u00ba eixo.<\/p>\n<p>\u201cUm trabalho permanente para promovermos melhorias nas estradas vicinais do nosso munic\u00edpio\u201d, destacou.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>&gt;&gt;&gt; VEJA OS V\u00cdDEOS ABAIXO:<\/strong><\/p>\n<p><iframe loading=\"lazy\" title=\"www.extraderondonia.com.br - Prefeito agradece benef\u00edcio de Luizinho em Colorado\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/HyKt409q2DE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"www.extraderondonia.com.br-Prefeito de Colorado anuncia recupera\u00e7\u00e3o de ponte na linha zero 1\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/gs63QTGndCI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em um v\u00eddeo de pouco mais de 1 minutos, o prefeito de Colorado do Oeste, Jos\u00e9 Ribamar, agradeceu o deputado estadual Luizinho Goebel pela emenda que destinou para a aquisi\u00e7\u00e3o de 120 metros de tubo armico. O an\u00fancio aconteceu na \u00faltima quarta-feira, 1\u00ba de julho, n\u00e3o p\u00e1tio da secretaria municipal de infraestrutura, com gestores da [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":307347,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-307346","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conesul"],"_links":{"self":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/307346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/comments?post=307346"}],"version-history":[{"count":0,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/307346\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media\/307347"}],"wp:attachment":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media?parent=307346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/categories?post=307346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/tags?post=307346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}