{"id":363354,"date":"2022-04-04T16:48:45","date_gmt":"2022-04-04T20:48:45","guid":{"rendered":"https:\/\/www.extraderondonia.com.br\/?p=363354"},"modified":"2022-04-06T16:49:16","modified_gmt":"2022-04-06T20:49:16","slug":"em-vilhena-pm-localiza-picape-roubada-de-medico-em-colorado-e-prende-suspeito-de-20-anos","status":"publish","type":"post","link":"https:\/\/www.extraderondonia.com.br\/sistema\/2022\/04\/04\/em-vilhena-pm-localiza-picape-roubada-de-medico-em-colorado-e-prende-suspeito-de-20-anos\/","title":{"rendered":"Em Vilhena, PM localiza picape roubada de m\u00e9dico em Colorado e prende suspeito de 20 anos"},"content":{"rendered":"<figure id=\"attachment_363360\" aria-describedby=\"caption-attachment-363360\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-363360 size-medium\" src=\"https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2022\/04\/f59c6dc8-e745-44ac-9bfd-b54f53d4fd1b-300x212.jpg\" alt=\"\" width=\"300\" height=\"212\" srcset=\"https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2022\/04\/f59c6dc8-e745-44ac-9bfd-b54f53d4fd1b-300x212.jpg 300w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2022\/04\/f59c6dc8-e745-44ac-9bfd-b54f53d4fd1b-600x423.jpg 600w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2022\/04\/f59c6dc8-e745-44ac-9bfd-b54f53d4fd1b-100x70.jpg 100w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2022\/04\/f59c6dc8-e745-44ac-9bfd-b54f53d4fd1b-696x491.jpg 696w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2022\/04\/f59c6dc8-e745-44ac-9bfd-b54f53d4fd1b-595x420.jpg 595w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2022\/04\/f59c6dc8-e745-44ac-9bfd-b54f53d4fd1b.jpg 710w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-363360\" class=\"wp-caption-text\">Momento da pris\u00e3o do suspeito e recupera\u00e7\u00e3o do ve\u00edculo pelos policiais militares de Vilhena e Colorado do Oeste\/Foto: Extra de Rond\u00f4nia<\/figcaption><\/figure>\n<p>Ap\u00f3s o registro da ocorr\u00eancia dando conta do roubo de uma caminhonete S-10 de cor vermelha, com placas e Vilhena, de propriedade de um m\u00e9dico da cidade de Colorado do Oeste, leia (<a href=\"https:\/\/www.extraderondonia.com.br\/2022\/04\/04\/medico-da-carona-a-desconhecidos-e-tem-caminhonete-roubada-em-colorado\/\">AQUI<\/a>) policiais militares daquele munic\u00edpio com apoio de policiais de Vilhena, localizaram o ve\u00edculo e prenderam um suspeito.<\/p>\n<p>Ap\u00f3s investiga\u00e7\u00e3o, os militares localizaram o ve\u00edculo na tarde desta segunda-feira, 4, na Avenida 737 com a Rua 1507, no bairro Cristo Rei, em Vilhena.<\/p>\n<p>Um jovem identificado pelas iniciais W.S.A.M., de 20 anos, foi detido como principal suspeito de ter cometido o crime.<\/p>\n<p>O rapaz ser\u00e1 levado para a Unidade Integrada de Seguran\u00e7a P\u00fablica (Unisp) de Colorado, onde ficar\u00e1 a disposi\u00e7\u00e3o da justi\u00e7a.<\/p>\n<figure id=\"attachment_363360\" aria-describedby=\"caption-attachment-363360\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-363360 size-large\" src=\"https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2022\/04\/f59c6dc8-e745-44ac-9bfd-b54f53d4fd1b-600x423.jpg\" alt=\"\" width=\"600\" height=\"423\" srcset=\"https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2022\/04\/f59c6dc8-e745-44ac-9bfd-b54f53d4fd1b-600x423.jpg 600w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2022\/04\/f59c6dc8-e745-44ac-9bfd-b54f53d4fd1b-300x212.jpg 300w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2022\/04\/f59c6dc8-e745-44ac-9bfd-b54f53d4fd1b-100x70.jpg 100w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2022\/04\/f59c6dc8-e745-44ac-9bfd-b54f53d4fd1b-696x491.jpg 696w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2022\/04\/f59c6dc8-e745-44ac-9bfd-b54f53d4fd1b-595x420.jpg 595w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2022\/04\/f59c6dc8-e745-44ac-9bfd-b54f53d4fd1b.jpg 710w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-363360\" class=\"wp-caption-text\">Momento da pris\u00e3o do suspeito e recupera\u00e7\u00e3o do ve\u00edculo pelos policiais militares de Vilhena e Colorado do Oeste\/Foto: Extra de Rond\u00f4nia<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s o registro da ocorr\u00eancia dando conta do roubo de uma caminhonete S-10 de cor vermelha, com placas e Vilhena, de propriedade de um m\u00e9dico da cidade de Colorado do Oeste, leia (AQUI) policiais militares daquele munic\u00edpio com apoio de policiais de Vilhena, localizaram o ve\u00edculo e prenderam um suspeito. Ap\u00f3s investiga\u00e7\u00e3o, os militares localizaram [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":363360,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-363354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conesul"],"_links":{"self":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/363354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/comments?post=363354"}],"version-history":[{"count":0,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/363354\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media\/363360"}],"wp:attachment":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media?parent=363354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/categories?post=363354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/tags?post=363354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}