{"id":372786,"date":"2022-08-05T08:40:55","date_gmt":"2022-08-05T12:40:55","guid":{"rendered":"https:\/\/www.extraderondonia.com.br\/?p=372786"},"modified":"2022-08-05T08:40:55","modified_gmt":"2022-08-05T12:40:55","slug":"acusado-de-matar-adolescente-pode-estar-escondido-no-acre-policiais-fazem-buscas","status":"publish","type":"post","link":"https:\/\/www.extraderondonia.com.br\/sistema\/2022\/08\/05\/acusado-de-matar-adolescente-pode-estar-escondido-no-acre-policiais-fazem-buscas\/","title":{"rendered":"Acusado de matar adolescente pode estar escondido no Acre; policiais fazem buscas"},"content":{"rendered":"<figure id=\"attachment_372788\" aria-describedby=\"caption-attachment-372788\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-372788\" src=\"https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2022\/08\/8q9b6g2ehwtm-300x291.jpg\" alt=\"\" width=\"300\" height=\"291\" srcset=\"https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2022\/08\/8q9b6g2ehwtm-300x291.jpg 300w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2022\/08\/8q9b6g2ehwtm-434x420.jpg 434w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2022\/08\/8q9b6g2ehwtm.jpg 506w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-372788\" class=\"wp-caption-text\">Foto: divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p>A 2\u00aa Delegacia de Homic\u00eddios de Porto Velho pede ajuda da popula\u00e7\u00e3o para localizar e prender temporariamente o foragido Luiz Gabriel Vinhorque, 18 anos, que pode estar escondido em Cruzeiro do Sul, no estado do Acre.<\/p>\n<p>Ele \u00e9 acusado de ter matado com um tiro na cabe\u00e7a o adolescente Arthur Amora Ribeiro, 13 anos, no final da tarde do \u00faltimo domingo (31), na rua Quintino Bocai\u00fava, no bairro S\u00e3o Cristov\u00e3o, na capital, onde ele brincava de empinar papagaios.<\/p>\n<p>Segundo o delegado Jos\u00e9 Marcos, Arthur morreu por engano. Luiz queria acertar os disparos em outro adolescente, com quem teria discutido cerca de meia hora antes do crime, por causa de papagaios. \u201cO acusado teria se aproveitado que um grupo de motociclistas passava pelo local, se infiltrou e efetuou os disparos, que n\u00e3o atingiram o verdadeiro alvo, mas sim Arthur. A arma que ele usou, estava escondida em sua motocicleta, em um compartimento. Ap\u00f3s efetuar os tiros, Luiz fugiu do local\u201d, disse o delegado.<\/p>\n<p>O delegado destacou ainda, que Luiz n\u00e3o era morador da regi\u00e3o onde ocorreu o crime. \u201cEle morava na zona sul da capital e foi para aquele bairro empinar pipa, quando houve o desentendimento com outra pessoa\u201d, disse.<\/p>\n<p>Durante as investiga\u00e7\u00f5es, policiais da 2\u00aa Delegacia de Homic\u00eddios, conseguiram imagens de c\u00e2meras de seguran\u00e7a, que mostram a discuss\u00e3o do acusado com outro rapaz.<\/p>\n<p>A Pol\u00edcia Civil afirma que o grupo de motociclistas que passavam pelo local, no momento do crime, n\u00e3o tem a ver com o assassinato de Arthur. \u201cO acusado se aproveitou do momento em que o grupo passava pelo local, para efetuar os disparos\u201d, disse Jos\u00e9 Marcos.<\/p>\n<p>Ap\u00f3s cometer o assassinato do adolescente, Luiz fugiu do estado de Rond\u00f4nia. Com sua identifica\u00e7\u00e3o, o delegado Cicero Cavalcante, representou pela pris\u00e3o tempor\u00e1ria do acusado e agora ele \u00e9 considerado foragido da justi\u00e7a.<\/p>\n<p>A Pol\u00edcia acredita que Luiz pode estar escondido no Estado do Acre. As for\u00e7as policiais daquele estado j\u00e1 foram acionadas. Policiais de Rond\u00f4nia chegaram a informar o endere\u00e7o onde o foragido estava, no Acre, mas quando a Pol\u00edcia chegou, ele fugiu pulando o muro da casa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A 2\u00aa Delegacia de Homic\u00eddios de Porto Velho pede ajuda da popula\u00e7\u00e3o para localizar e prender temporariamente o foragido Luiz Gabriel Vinhorque, 18 anos, que pode estar escondido em Cruzeiro do Sul, no estado do Acre. Ele \u00e9 acusado de ter matado com um tiro na cabe\u00e7a o adolescente Arthur Amora Ribeiro, 13 anos, no [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":372788,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-372786","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial"],"_links":{"self":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/372786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/comments?post=372786"}],"version-history":[{"count":0,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/372786\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media\/372788"}],"wp:attachment":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media?parent=372786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/categories?post=372786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/tags?post=372786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}