{"id":52822,"date":"2014-10-03T12:16:35","date_gmt":"2014-10-03T16:16:35","guid":{"rendered":"http:\/\/www.extraderondonia.com.br\/?p=52822"},"modified":"2014-10-03T16:19:09","modified_gmt":"2014-10-03T20:19:09","slug":"justica-ira-julgar-indenizacao-as-vitimas-do-massacre-de-corumbiara","status":"publish","type":"post","link":"https:\/\/www.extraderondonia.com.br\/sistema\/2014\/10\/03\/justica-ira-julgar-indenizacao-as-vitimas-do-massacre-de-corumbiara\/","title":{"rendered":"Justi\u00e7a ir\u00e1 julgar indeniza\u00e7\u00e3o \u00e0s v\u00edtimas do &#8220;Massacre de Corumbiara&#8221;"},"content":{"rendered":"<p><a href=\"http:\/\/www.extraderondonia.com.br\/2014\/10\/03\/justica-ira-julgar-indenizacao-as-vitimas-do-massacre-de-corumbiara\/corumb\/\" rel=\"attachment wp-att-52823\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-52823\" src=\"http:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2014\/10\/corumb-300x198.jpg\" alt=\"corumb\" width=\"300\" height=\"198\" srcset=\"https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2014\/10\/corumb-300x198.jpg 300w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2014\/10\/corumb.jpg 454w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Audi\u00eancia de Instru\u00e7\u00e3o e Julgamento de indeniza\u00e7\u00e3o \u00e0s v\u00edtimas do Massacre de Corumbiara est\u00e1 marcada para o pr\u00f3ximo m\u00eas.<\/p>\n<p>Essa confirma\u00e7\u00e3o era aguardada desde 2010, quando a Federa\u00e7\u00e3o dos Trabalhadores na Agricultura de Rond\u00f4nia (Fetagro) desenvolveu um trabalho em conjunto com o Minist\u00e9rio dos Direitos Humanos a fim de reivindicar a justi\u00e7a social em favor das v\u00edtimas do massacre, considerado um dos piores registros de conflitos agr\u00e1rios na hist\u00f3ria do Estado de Rond\u00f4nia.<\/p>\n<p>O advogado Neumayer Pereira de Souza ingressou com a\u00e7\u00e3o em beneficio de 204 v\u00edtimas, em janeiro daquele ano, e ap\u00f3s as providencias preliminares, o Juiz da 2\u00aa Vara da Fazenda Publico de Porto Velho, onde tramita o processo, proferiu o despacho saneador no processo e designou o dia 18 de novembro pr\u00f3ximo, para a realiza\u00e7\u00e3o da audi\u00eancia de instru\u00e7\u00e3o e julgamento, quando ser\u00e3o ouvidas as v\u00edtimas, todas trabalhadoras rurais, e as testemunhas arroladas.<\/p>\n<p>O conflito, ocorrido no dia 09 de agosto de 1995 entre trabalhadores rurais e policiais militares, em ocasi\u00e3o de cumprimento de mandato judicial de reintegra\u00e7\u00e3o de posse, em \u00e1rea da fazenda Santa Elina, no munic\u00edpio de Corumbiara, regi\u00e3o Sul do Estado, ficou conhecido internacionalmente e marcou a hist\u00f3ria de luta pela conquista da terra em Rond\u00f4nia.<\/p>\n<p>Segundo relatos, naquele dia, cerca de 600 camponeses ocupantes da \u00e1rea considerada improdutiva foram surpreendidos durante a madrugada do dia 9 com o ataque de pistoleiros armados e soldados da Pol\u00edcia Militar. Um violento confronto foi desencadeado, resultando em mortes, torturas, insultos e humilha\u00e7\u00f5es aos trabalhadores e trabalhadoras. Ao Estado de Rond\u00f4nia \u00e9 atribu\u00edda culpa e, portanto, reivindicada condena\u00e7\u00e3o de indeniza\u00e7\u00e3o, quando da comprova\u00e7\u00e3o da conduta excessiva dos policiais, que, por certo, tinham condi\u00e7\u00f5es de executar a ordem judicial (a reintegra\u00e7\u00e3o de posse), sem que o resultado fosse o que veio a ocorrer; e dos danos sofridos por aqueles que estavam presentes no conflito.<br \/>\nTexto: Assessoria<\/p>\n<p>Foto: Divulga\u00e7\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Audi\u00eancia de Instru\u00e7\u00e3o e Julgamento de indeniza\u00e7\u00e3o \u00e0s v\u00edtimas do Massacre de Corumbiara est\u00e1 marcada para o pr\u00f3ximo m\u00eas. Essa confirma\u00e7\u00e3o era aguardada desde 2010, quando a Federa\u00e7\u00e3o dos Trabalhadores na Agricultura de Rond\u00f4nia (Fetagro) desenvolveu um trabalho em conjunto com o Minist\u00e9rio dos Direitos Humanos a fim de reivindicar a justi\u00e7a social em favor [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":52823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-52822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/52822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/comments?post=52822"}],"version-history":[{"count":0,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/52822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media\/52823"}],"wp:attachment":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media?parent=52822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/categories?post=52822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/tags?post=52822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}