{"id":72141,"date":"2015-03-09T09:21:11","date_gmt":"2015-03-09T13:21:11","guid":{"rendered":"http:\/\/www.extraderondonia.com.br\/?p=72141"},"modified":"2015-03-09T09:21:11","modified_gmt":"2015-03-09T13:21:11","slug":"moradora-de-corumbiara-ganha-cadeira-sorteada-pelo-extra-de-rondonia","status":"publish","type":"post","link":"https:\/\/www.extraderondonia.com.br\/sistema\/2015\/03\/09\/moradora-de-corumbiara-ganha-cadeira-sorteada-pelo-extra-de-rondonia\/","title":{"rendered":"Moradora de Corumbiara ganha cadeira sorteada pelo Extra de Rond\u00f4nia"},"content":{"rendered":"<p><a href=\"http:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2015\/03\/cadeira.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-72142\" src=\"http:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2015\/03\/cadeira-300x225.jpg\" alt=\"cadeira\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2015\/03\/cadeira-300x225.jpg 300w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2015\/03\/cadeira-80x60.jpg 80w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2015\/03\/cadeira-265x198.jpg 265w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2015\/03\/cadeira-560x420.jpg 560w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2015\/03\/cadeira-600x450.jpg 600w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2015\/03\/cadeira-294x221.jpg 294w, https:\/\/www.extraderondonia.com.br\/sistema\/wp-content\/uploads\/2015\/03\/cadeira.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>O mec\u00e2nico Rosildo de Souza Aires, de 23 anos, trabalha transformando pneus descartados em v\u00e1rios tipos de artesanatos como jogos de mesa, cisnes e xicaras.<\/p>\n<p>Rosildo divulga seus produtos na p\u00e1gina do Facebook \u201cArte com pneus em Rond\u00f4nia\u201d. Rosildo ressalta que seu trabalho ajuda a preservar o meio ambiente, pois ele recolhe pneus usados das ruas e mec\u00e2nicas da cidade dando um novo destino para esse material.<\/p>\n<p>Para as pessoas que desejam conhecer o trabalho de Rosildo podem acessar p\u00e1gina do Facebook \u201cArte com pneus em Rond\u00f4nia\u201d, ou ir \u00e0 Avenida 1701, n\u00famero 1083 no bairro Jardim Primavera, em Vilhena.<\/p>\n<p>Em parceria com Rosildo o <strong><em>Extra de Rond\u00f4nia<\/em><\/strong> sorteou uma cadeira produzida pelo artes\u00e3o. A ganhadora pode retirar a cadeira entrando em contato com Rosildo pelos telefones (69) 3321-1089 ou 8447-7271.<\/p>\n<p><em>Veja o nome da ganhadora:<\/em><\/p>\n<p>** W\u00e9rica Greici da Silva de Santana, moradora de Corumbiara.<\/p>\n<p>Texto: Extra de Rond\u00f4nia<\/p>\n<p>Fotos: Divulga\u00e7\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O mec\u00e2nico Rosildo de Souza Aires, de 23 anos, trabalha transformando pneus descartados em v\u00e1rios tipos de artesanatos como jogos de mesa, cisnes e xicaras. Rosildo divulga seus produtos na p\u00e1gina do Facebook \u201cArte com pneus em Rond\u00f4nia\u201d. Rosildo ressalta que seu trabalho ajuda a preservar o meio ambiente, pois ele recolhe pneus usados das [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":72142,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,12],"tags":[],"class_list":["post-72141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/72141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/comments?post=72141"}],"version-history":[{"count":0,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/posts\/72141\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media\/72142"}],"wp:attachment":[{"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/media?parent=72141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/categories?post=72141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.extraderondonia.com.br\/sistema\/wp-json\/wp\/v2\/tags?post=72141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}